{"id":8,"date":"2025-09-26T21:59:16","date_gmt":"2025-09-26T21:59:16","guid":{"rendered":"https:\/\/edifica.com.py\/?page_id=8"},"modified":"2025-10-13T22:21:38","modified_gmt":"2025-10-13T22:21:38","slug":"elementor-8","status":"publish","type":"page","link":"https:\/\/edifica.com.py","title":{"rendered":"\u00bfQui\u00e9nes somos?"},"content":{"rendered":"\n<p class=\"is-style-text-display--1\" style=\"font-style: normal; font-weight: 400;\">\u00bfTienes preguntas? <br \/>No dudes en ponerte en contacto con nosotros.<\/p>\n<p style=\"font-style: normal; font-weight: 400;\"><!-- \/wp:post-content --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|80\",\"bottom\":\"var:preset|spacing|80\"},\"blockGap\":\"var:preset|spacing|50\",\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:paragraph {\"align\":\"center\",\"className\":\"is-style-text-display\",\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"400\"}}} -->\n<p style=\"font-style: normal; font-weight: 400;\">\u00bfTienes preguntas? <br \/>No dudes en ponerte en contacto con nosotros.<\/p>\n<p style=\"font-style: normal; font-weight: 400;\"><!-- \/wp:paragraph --><!-- \/wp:group --><!-- \/wp:group --><!-- wp:post-content --><\/p>\n<!-- wp:cover {\"url\":\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/northern-buttercups-flowers.webp\",\"alt\":\"Foto de una flor\",\"dimRatio\":10,\"focalPoint\":{\"x\":0.5,\"y\":0.9499999999999999555910790149937383830547332763671875},\"minHeight\":840,\"minHeightUnit\":\"px\",\"contentPosition\":\"bottom center\",\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\",\"left\":\"var:preset|spacing|50\",\"right\":\"var:preset|spacing|50\"},\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<img decoding=\"async\" style=\"object-position: 50% 95%;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/northern-buttercups-flowers.webp\" alt=\"Foto de una flor\" data-object-fit=\"cover\" data-object-position=\"50% 95%\" \/>\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"constrained\",\"justifyContent\":\"left\"}} -->\n<!-- wp:heading {\"textAlign\":\"left\",\"fontSize\":\"xx-large\"} -->\n<h2>Nuestra misi\u00f3n<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Crear desarrollos inmobiliarios de alto impacto que combinen dise\u00f1o arquitect\u00f3nico innovador, calidad constructiva y valor sostenible, ofreciendo a nuestros clientes espacios que se conviertan en legado familiar, oportunidades de inversi\u00f3n seguras y motores de crecimiento urbano para las ciudades donde operamos.<\/p>\n<!-- \/wp:paragraph --><!-- wp:buttons -->\n<!-- wp:button -->\n<a>Saber m\u00e1s<\/a>\n<!-- \/wp:button -->\n<!-- \/wp:buttons -->\n<!-- \/wp:group -->\n<!-- \/wp:cover --><!-- wp:group {\"align\":\"full\",\"className\":\"is-style-section-5\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:columns {\"align\":\"wide\",\"style\":{\"spacing\":{\"blockGap\":{\"top\":\"var:preset|spacing|60\",\"left\":\"var:preset|spacing|80\"}}}} -->\n<!-- wp:column {\"verticalAlignment\":\"center\",\"width\":\"50%\"} -->\n<!-- wp:heading {\"className\":\"wp-block-heading\"} -->\n<h2>Nuestra visi\u00f3n<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p>Ser la desarrolladora inmobiliaria referente en Paraguay y la regi\u00f3n, reconocida por proyectos premium que integran modernidad, arquitectura de vanguardia y sentido humano, consolidando un portafolio s\u00f3lido y atemporal que marque tendencia y genere confianza en inversores nacionales e internacionales.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:column --><!-- wp:column {\"verticalAlignment\":\"center\",\"width\":\"50%\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:image {\"aspectRatio\":\"1\",\"scale\":\"cover\",\"sizeSlug\":\"full\"} -->\n<figure><img fetchpriority=\"high\" decoding=\"async\" style=\"aspect-ratio: 1; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/ruins-image.webp\" alt=\"Cliff Palace, Colorado\" width=\"678\" height=\"677\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:column -->\n<!-- \/wp:columns -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"grid\",\"minimumColumnWidth\":\"26rem\"}} -->\n<!-- wp:group {\"style\":{\"spacing\":{\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"flex\",\"orientation\":\"vertical\",\"verticalAlignment\":\"space-between\",\"justifyContent\":\"stretch\",\"flexWrap\":\"nowrap\"}} -->\n<!-- wp:group {\"layout\":{\"type\":\"flex\",\"orientation\":\"vertical\",\"justifyContent\":\"left\"}} -->\n<!-- wp:heading {\"className\":\"is-style-text-annotation\"} -->\n<h2>Nuestro Valores<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph {\"className\":\"is-style-text-subtitle\"} -->\n<p><strong>Fleurs<\/strong> es una empresa de env\u00edo y suscripci\u00f3n de flores. Con sede en la UE, nuestra misi\u00f3n no es s\u00f3lo entregar impresionantes arreglos florales en todo el mundo, sino tambi\u00e9n fomentar el conocimiento y el entusiasmo sobre este hermoso regalo de la naturaleza: las flores.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group --><!-- wp:image {\"aspectRatio\":\"16\/9\",\"scale\":\"cover\",\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure><img decoding=\"async\" style=\"aspect-ratio: 16\/9; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/grid-flower-1.webp\" alt=\"Primer plano fotogr\u00e1fico de una flor roja.\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:group --><!-- wp:image {\"aspectRatio\":\"3\/4\",\"scale\":\"cover\",\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure><img decoding=\"async\" style=\"aspect-ratio: 3\/4; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/grid-flower-2.webp\" alt=\"Fotograf\u00eda en blanco y negro primer plano de una flor.\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:group -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"fontSize\":\"x-large\"} -->\n<h2>Preguntas m\u00e1s frecuentes<\/h2>\n<!-- \/wp:heading --><!-- wp:columns {\"style\":{\"spacing\":{\"blockGap\":{\"left\":\"var:preset|spacing|50\"}}}} -->\n<!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfDe qu\u00e9 trata El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column --><!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfCu\u00e1nto cuesta El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column -->\n<!-- \/wp:columns --><!-- wp:columns {\"style\":{\"spacing\":{\"blockGap\":{\"left\":\"var:preset|spacing|50\"}}}} -->\n<!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfCu\u00e1ndo saldr\u00e1 a la venta El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column --><!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfHay ejemplares firmados disponibles?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column -->\n<!-- \/wp:columns -->\n<!-- \/wp:group -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|80\",\"bottom\":\"var:preset|spacing|80\"},\"blockGap\":\"var:preset|spacing|50\",\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:paragraph {\"align\":\"center\",\"className\":\"is-style-text-display\",\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"400\"}}} -->\n<p style=\"font-style: normal; font-weight: 400;\">\u00bfTienes preguntas? <br \/>No dudes en ponerte en contacto con nosotros.<\/p>\n<p style=\"font-style: normal; font-weight: 400;\"><!-- \/wp:paragraph --><!-- \/wp:group --><!-- \/wp:group --><!-- \/wp:post-content --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|80\",\"bottom\":\"var:preset|spacing|80\"},\"blockGap\":\"var:preset|spacing|50\",\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:paragraph {\"align\":\"center\",\"className\":\"is-style-text-display\",\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"400\"}}} -->\n<p style=\"font-style: normal; font-weight: 400;\">\u00bfTienes preguntas? <br \/>No dudes en ponerte en contacto con nosotros.<\/p>\n<p style=\"font-style: normal; font-weight: 400;\"><!-- \/wp:paragraph --><!-- \/wp:group --><!-- wp:post-content --><\/p>\n<!-- wp:cover {\"url\":\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/northern-buttercups-flowers.webp\",\"alt\":\"Foto de una flor\",\"dimRatio\":10,\"focalPoint\":{\"x\":0.5,\"y\":0.9499999999999999555910790149937383830547332763671875},\"minHeight\":840,\"minHeightUnit\":\"px\",\"contentPosition\":\"bottom center\",\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\",\"left\":\"var:preset|spacing|50\",\"right\":\"var:preset|spacing|50\"},\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<img decoding=\"async\" style=\"object-position: 50% 95%;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/northern-buttercups-flowers.webp\" alt=\"Foto de una flor\" data-object-fit=\"cover\" data-object-position=\"50% 95%\" \/>\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"constrained\",\"justifyContent\":\"left\"}} -->\n<!-- wp:heading {\"textAlign\":\"left\",\"fontSize\":\"xx-large\"} -->\n<h2>Nuestra misi\u00f3n<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Crear desarrollos inmobiliarios de alto impacto que combinen dise\u00f1o arquitect\u00f3nico innovador, calidad constructiva y valor sostenible, ofreciendo a nuestros clientes espacios que se conviertan en legado familiar, oportunidades de inversi\u00f3n seguras y motores de crecimiento urbano para las ciudades donde operamos.<\/p>\n<!-- \/wp:paragraph --><!-- wp:buttons -->\n<!-- wp:button -->\n<a>Saber m\u00e1s<\/a>\n<!-- \/wp:button -->\n<!-- \/wp:buttons -->\n<!-- \/wp:group -->\n<!-- \/wp:cover --><!-- wp:group {\"align\":\"full\",\"className\":\"is-style-section-5\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:columns {\"align\":\"wide\",\"style\":{\"spacing\":{\"blockGap\":{\"top\":\"var:preset|spacing|60\",\"left\":\"var:preset|spacing|80\"}}}} -->\n<!-- wp:column {\"verticalAlignment\":\"center\",\"width\":\"50%\"} -->\n<!-- wp:heading {\"className\":\"wp-block-heading\"} -->\n<h2>Nuestra visi\u00f3n<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p>Ser la desarrolladora inmobiliaria referente en Paraguay y la regi\u00f3n, reconocida por proyectos premium que integran modernidad, arquitectura de vanguardia y sentido humano, consolidando un portafolio s\u00f3lido y atemporal que marque tendencia y genere confianza en inversores nacionales e internacionales.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:column --><!-- wp:column {\"verticalAlignment\":\"center\",\"width\":\"50%\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:image {\"aspectRatio\":\"1\",\"scale\":\"cover\",\"sizeSlug\":\"full\"} -->\n<figure><img fetchpriority=\"high\" decoding=\"async\" style=\"aspect-ratio: 1; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/ruins-image.webp\" alt=\"Cliff Palace, Colorado\" width=\"678\" height=\"677\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:column -->\n<!-- \/wp:columns -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"grid\",\"minimumColumnWidth\":\"26rem\"}} -->\n<!-- wp:group {\"style\":{\"spacing\":{\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"flex\",\"orientation\":\"vertical\",\"verticalAlignment\":\"space-between\",\"justifyContent\":\"stretch\",\"flexWrap\":\"nowrap\"}} -->\n<!-- wp:group {\"layout\":{\"type\":\"flex\",\"orientation\":\"vertical\",\"justifyContent\":\"left\"}} -->\n<!-- wp:heading {\"className\":\"is-style-text-annotation\"} -->\n<h2>Nuestro Valores<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph {\"className\":\"is-style-text-subtitle\"} -->\n<p><strong>Fleurs<\/strong> es una empresa de env\u00edo y suscripci\u00f3n de flores. Con sede en la UE, nuestra misi\u00f3n no es s\u00f3lo entregar impresionantes arreglos florales en todo el mundo, sino tambi\u00e9n fomentar el conocimiento y el entusiasmo sobre este hermoso regalo de la naturaleza: las flores.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group --><!-- wp:image {\"aspectRatio\":\"16\/9\",\"scale\":\"cover\",\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure><img decoding=\"async\" style=\"aspect-ratio: 16\/9; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/grid-flower-1.webp\" alt=\"Primer plano fotogr\u00e1fico de una flor roja.\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:group --><!-- wp:image {\"aspectRatio\":\"3\/4\",\"scale\":\"cover\",\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure><img decoding=\"async\" style=\"aspect-ratio: 3\/4; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/grid-flower-2.webp\" alt=\"Fotograf\u00eda en blanco y negro primer plano de una flor.\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:group -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"fontSize\":\"x-large\"} -->\n<h2>Preguntas m\u00e1s frecuentes<\/h2>\n<!-- \/wp:heading --><!-- wp:columns {\"style\":{\"spacing\":{\"blockGap\":{\"left\":\"var:preset|spacing|50\"}}}} -->\n<!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfDe qu\u00e9 trata El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column --><!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfCu\u00e1nto cuesta El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column -->\n<!-- \/wp:columns --><!-- wp:columns {\"style\":{\"spacing\":{\"blockGap\":{\"left\":\"var:preset|spacing|50\"}}}} -->\n<!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfCu\u00e1ndo saldr\u00e1 a la venta El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column --><!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfHay ejemplares firmados disponibles?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column -->\n<!-- \/wp:columns -->\n<!-- \/wp:group -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|80\",\"bottom\":\"var:preset|spacing|80\"},\"blockGap\":\"var:preset|spacing|50\",\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:paragraph {\"align\":\"center\",\"className\":\"is-style-text-display\",\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"400\"}}} -->\n<p style=\"font-style: normal; font-weight: 400;\">\u00bfTienes preguntas? <br \/>No dudes en ponerte en contacto con nosotros.<\/p>\n<p style=\"font-style: normal; font-weight: 400;\"><!-- \/wp:post-content --><!-- \/wp:post-content --><!-- \/wp:post-content --><!-- \/wp:group --><!-- wp:post-content --><\/p>\n<!-- wp:cover {\"url\":\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/northern-buttercups-flowers.webp\",\"alt\":\"Foto de una flor\",\"dimRatio\":10,\"focalPoint\":{\"x\":0.5,\"y\":0.9499999999999999555910790149937383830547332763671875},\"minHeight\":840,\"minHeightUnit\":\"px\",\"contentPosition\":\"bottom center\",\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\",\"left\":\"var:preset|spacing|50\",\"right\":\"var:preset|spacing|50\"},\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<img decoding=\"async\" style=\"object-position: 50% 95%;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/northern-buttercups-flowers.webp\" alt=\"Foto de una flor\" data-object-fit=\"cover\" data-object-position=\"50% 95%\" \/>\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"constrained\",\"justifyContent\":\"left\"}} -->\n<!-- wp:heading {\"textAlign\":\"left\",\"fontSize\":\"xx-large\"} -->\n<h2>Nuestra misi\u00f3n<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Crear desarrollos inmobiliarios de alto impacto que combinen dise\u00f1o arquitect\u00f3nico innovador, calidad constructiva y valor sostenible, ofreciendo a nuestros clientes espacios que se conviertan en legado familiar, oportunidades de inversi\u00f3n seguras y motores de crecimiento urbano para las ciudades donde operamos.<\/p>\n<!-- \/wp:paragraph --><!-- wp:buttons -->\n<!-- wp:button -->\n<a>Saber m\u00e1s<\/a>\n<!-- \/wp:button -->\n<!-- \/wp:buttons -->\n<!-- \/wp:group -->\n<!-- \/wp:cover --><!-- wp:group {\"align\":\"full\",\"className\":\"is-style-section-5\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:columns {\"align\":\"wide\",\"style\":{\"spacing\":{\"blockGap\":{\"top\":\"var:preset|spacing|60\",\"left\":\"var:preset|spacing|80\"}}}} -->\n<!-- wp:column {\"verticalAlignment\":\"center\",\"width\":\"50%\"} -->\n<!-- wp:heading {\"className\":\"wp-block-heading\"} -->\n<h2>Nuestra visi\u00f3n<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p>Ser la desarrolladora inmobiliaria referente en Paraguay y la regi\u00f3n, reconocida por proyectos premium que integran modernidad, arquitectura de vanguardia y sentido humano, consolidando un portafolio s\u00f3lido y atemporal que marque tendencia y genere confianza en inversores nacionales e internacionales.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:column --><!-- wp:column {\"verticalAlignment\":\"center\",\"width\":\"50%\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:image {\"aspectRatio\":\"1\",\"scale\":\"cover\",\"sizeSlug\":\"full\"} -->\n<figure><img fetchpriority=\"high\" decoding=\"async\" style=\"aspect-ratio: 1; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/ruins-image.webp\" alt=\"Cliff Palace, Colorado\" width=\"678\" height=\"677\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:column -->\n<!-- \/wp:columns -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"grid\",\"minimumColumnWidth\":\"26rem\"}} -->\n<!-- wp:group {\"style\":{\"spacing\":{\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"flex\",\"orientation\":\"vertical\",\"verticalAlignment\":\"space-between\",\"justifyContent\":\"stretch\",\"flexWrap\":\"nowrap\"}} -->\n<!-- wp:group {\"layout\":{\"type\":\"flex\",\"orientation\":\"vertical\",\"justifyContent\":\"left\"}} -->\n<!-- wp:heading {\"className\":\"is-style-text-annotation\"} -->\n<h2>Nuestro Valores<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph {\"className\":\"is-style-text-subtitle\"} -->\n<p><strong>Fleurs<\/strong> es una empresa de env\u00edo y suscripci\u00f3n de flores. Con sede en la UE, nuestra misi\u00f3n no es s\u00f3lo entregar impresionantes arreglos florales en todo el mundo, sino tambi\u00e9n fomentar el conocimiento y el entusiasmo sobre este hermoso regalo de la naturaleza: las flores.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group --><!-- wp:image {\"aspectRatio\":\"16\/9\",\"scale\":\"cover\",\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure><img decoding=\"async\" style=\"aspect-ratio: 16\/9; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/grid-flower-1.webp\" alt=\"Primer plano fotogr\u00e1fico de una flor roja.\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:group --><!-- wp:image {\"aspectRatio\":\"3\/4\",\"scale\":\"cover\",\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure><img decoding=\"async\" style=\"aspect-ratio: 3\/4; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/grid-flower-2.webp\" alt=\"Fotograf\u00eda en blanco y negro primer plano de una flor.\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:group -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"fontSize\":\"x-large\"} -->\n<h2>Preguntas m\u00e1s frecuentes<\/h2>\n<!-- \/wp:heading --><!-- wp:columns {\"style\":{\"spacing\":{\"blockGap\":{\"left\":\"var:preset|spacing|50\"}}}} -->\n<!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfDe qu\u00e9 trata El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column --><!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfCu\u00e1nto cuesta El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column -->\n<!-- \/wp:columns --><!-- wp:columns {\"style\":{\"spacing\":{\"blockGap\":{\"left\":\"var:preset|spacing|50\"}}}} -->\n<!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfCu\u00e1ndo saldr\u00e1 a la venta El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column --><!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfHay ejemplares firmados disponibles?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column -->\n<!-- \/wp:columns -->\n<!-- \/wp:group -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|80\",\"bottom\":\"var:preset|spacing|80\"},\"blockGap\":\"var:preset|spacing|50\",\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:paragraph {\"align\":\"center\",\"className\":\"is-style-text-display\",\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"400\"}}} -->\n<p style=\"font-style: normal; font-weight: 400;\">\u00bfTienes preguntas? <br \/>No dudes en ponerte en contacto con nosotros.<\/p>\n<p style=\"font-style: normal; font-weight: 400;\"><!-- \/wp:paragraph --><!-- \/wp:group --><!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|80\",\"bottom\":\"var:preset|spacing|80\"},\"blockGap\":\"var:preset|spacing|50\",\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:paragraph {\"align\":\"center\",\"className\":\"is-style-text-display\",\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"400\"}}} -->\n<p style=\"font-style: normal; font-weight: 400;\">\u00bfTienes preguntas? <br \/>No dudes en ponerte en contacto con nosotros.<\/p>\n<p style=\"font-style: normal; font-weight: 400;\"><!-- \/wp:paragraph --><!-- \/wp:group --><!-- wp:post-content --><\/p>\n<!-- wp:cover {\"url\":\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/northern-buttercups-flowers.webp\",\"alt\":\"Foto de una flor\",\"dimRatio\":10,\"focalPoint\":{\"x\":0.5,\"y\":0.9499999999999999555910790149937383830547332763671875},\"minHeight\":840,\"minHeightUnit\":\"px\",\"contentPosition\":\"bottom center\",\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\",\"left\":\"var:preset|spacing|50\",\"right\":\"var:preset|spacing|50\"},\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<img decoding=\"async\" style=\"object-position: 50% 95%;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/northern-buttercups-flowers.webp\" alt=\"Foto de una flor\" data-object-fit=\"cover\" data-object-position=\"50% 95%\" \/>\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"constrained\",\"justifyContent\":\"left\"}} -->\n<!-- wp:heading {\"textAlign\":\"left\",\"fontSize\":\"xx-large\"} -->\n<h2>Nuestra misi\u00f3n<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Crear desarrollos inmobiliarios de alto impacto que combinen dise\u00f1o arquitect\u00f3nico innovador, calidad constructiva y valor sostenible, ofreciendo a nuestros clientes espacios que se conviertan en legado familiar, oportunidades de inversi\u00f3n seguras y motores de crecimiento urbano para las ciudades donde operamos.<\/p>\n<!-- \/wp:paragraph --><!-- wp:buttons -->\n<!-- wp:button -->\n<a>Saber m\u00e1s<\/a>\n<!-- \/wp:button -->\n<!-- \/wp:buttons -->\n<!-- \/wp:group -->\n<!-- \/wp:cover --><!-- wp:group {\"align\":\"full\",\"className\":\"is-style-section-5\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:columns {\"align\":\"wide\",\"style\":{\"spacing\":{\"blockGap\":{\"top\":\"var:preset|spacing|60\",\"left\":\"var:preset|spacing|80\"}}}} -->\n<!-- wp:column {\"verticalAlignment\":\"center\",\"width\":\"50%\"} -->\n<!-- wp:heading {\"className\":\"wp-block-heading\"} -->\n<h2>Nuestra visi\u00f3n<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p>Ser la desarrolladora inmobiliaria referente en Paraguay y la regi\u00f3n, reconocida por proyectos premium que integran modernidad, arquitectura de vanguardia y sentido humano, consolidando un portafolio s\u00f3lido y atemporal que marque tendencia y genere confianza en inversores nacionales e internacionales.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:column --><!-- wp:column {\"verticalAlignment\":\"center\",\"width\":\"50%\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:image {\"aspectRatio\":\"1\",\"scale\":\"cover\",\"sizeSlug\":\"full\"} -->\n<figure><img fetchpriority=\"high\" decoding=\"async\" style=\"aspect-ratio: 1; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/ruins-image.webp\" alt=\"Cliff Palace, Colorado\" width=\"678\" height=\"677\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:column -->\n<!-- \/wp:columns -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"grid\",\"minimumColumnWidth\":\"26rem\"}} -->\n<!-- wp:group {\"style\":{\"spacing\":{\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"flex\",\"orientation\":\"vertical\",\"verticalAlignment\":\"space-between\",\"justifyContent\":\"stretch\",\"flexWrap\":\"nowrap\"}} -->\n<!-- wp:group {\"layout\":{\"type\":\"flex\",\"orientation\":\"vertical\",\"justifyContent\":\"left\"}} -->\n<!-- wp:heading {\"className\":\"is-style-text-annotation\"} -->\n<h2>Nuestro Valores<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph {\"className\":\"is-style-text-subtitle\"} -->\n<p><strong>Fleurs<\/strong> es una empresa de env\u00edo y suscripci\u00f3n de flores. Con sede en la UE, nuestra misi\u00f3n no es s\u00f3lo entregar impresionantes arreglos florales en todo el mundo, sino tambi\u00e9n fomentar el conocimiento y el entusiasmo sobre este hermoso regalo de la naturaleza: las flores.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group --><!-- wp:image {\"aspectRatio\":\"16\/9\",\"scale\":\"cover\",\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure><img decoding=\"async\" style=\"aspect-ratio: 16\/9; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/grid-flower-1.webp\" alt=\"Primer plano fotogr\u00e1fico de una flor roja.\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:group --><!-- wp:image {\"aspectRatio\":\"3\/4\",\"scale\":\"cover\",\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure><img decoding=\"async\" style=\"aspect-ratio: 3\/4; object-fit: cover;\" src=\"https:\/\/edifica.com.py\/wp-content\/themes\/twentytwentyfive\/assets\/images\/grid-flower-2.webp\" alt=\"Fotograf\u00eda en blanco y negro primer plano de una flor.\" \/><\/figure>\n<!-- \/wp:image -->\n<!-- \/wp:group -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|50\",\"bottom\":\"var:preset|spacing|50\"},\"blockGap\":\"var:preset|spacing|50\"}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"fontSize\":\"x-large\"} -->\n<h2>Preguntas m\u00e1s frecuentes<\/h2>\n<!-- \/wp:heading --><!-- wp:columns {\"style\":{\"spacing\":{\"blockGap\":{\"left\":\"var:preset|spacing|50\"}}}} -->\n<!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfDe qu\u00e9 trata El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column --><!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfCu\u00e1nto cuesta El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column -->\n<!-- \/wp:columns --><!-- wp:columns {\"style\":{\"spacing\":{\"blockGap\":{\"left\":\"var:preset|spacing|50\"}}}} -->\n<!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfCu\u00e1ndo saldr\u00e1 a la venta El libro de las historias?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column --><!-- wp:column -->\n<!-- wp:group {\"style\":{\"border\":{\"top\":{\"color\":\"var:preset|color|accent-6\",\"width\":\"1px\"}},\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|30\",\"bottom\":\"var:preset|spacing|30\"}}},\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:heading {\"level\":3} -->\n<h3>\u00bfHay ejemplares firmados disponibles?<\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Esta exquisita recopilaci\u00f3n muestra un conjunto diverso de fotograf\u00edas que captan la esencia de distintas \u00e9pocas y culturas, reflejando los estilos y perspectivas \u00fanicos de cada artista.<\/p>\n<!-- \/wp:paragraph -->\n<!-- \/wp:group -->\n<!-- \/wp:column -->\n<!-- \/wp:columns -->\n<!-- \/wp:group -->\n<!-- \/wp:group --><!-- wp:group {\"align\":\"full\",\"style\":{\"spacing\":{\"padding\":{\"top\":\"var:preset|spacing|80\",\"bottom\":\"var:preset|spacing|80\"},\"blockGap\":\"var:preset|spacing|50\",\"margin\":{\"top\":\"0\",\"bottom\":\"0\"}}},\"layout\":{\"type\":\"constrained\"}} -->\n<!-- wp:group {\"align\":\"wide\",\"layout\":{\"type\":\"default\"}} -->\n<!-- wp:paragraph {\"align\":\"center\",\"className\":\"is-style-text-display\",\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"400\"}}} -->\n<p style=\"font-style: normal; font-weight: 400;\">\u00bfTienes preguntas? <br \/>No dudes en ponerte en contacto con nosotros.<\/p>\n<p style=\"font-style: normal; font-weight: 400;\"><!-- \/wp:post-content --><!-- \/wp:post-content --><!-- \/wp:post-content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfTienes preguntas? No dudes en ponerte en contacto con nosotros. \u00bfTienes preguntas? No dudes en ponerte en contacto con nosotros. Nuestra misi\u00f3n Crear desarrollos inmobiliarios de alto impacto que combinen dise\u00f1o arquitect\u00f3nico innovador, calidad constructiva y valor sostenible, ofreciendo a nuestros clientes espacios que se conviertan en legado familiar, oportunidades de inversi\u00f3n seguras y motores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQui\u00e9nes somos?<\/title>\n<meta name=\"description\" content=\"Edifica es una desarrolladora inmobiliaria que nace con la visi\u00f3n de transformar el interior del pa\u00eds a trav\u00e9s de proyectos que eleven la calidad urbana y aporten valor real a las ciudades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edifica.com.py\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9nes somos?\" \/>\n<meta property=\"og:description\" content=\"Edifica es una desarrolladora inmobiliaria que nace con la visi\u00f3n de transformar el interior del pa\u00eds a trav\u00e9s de proyectos que eleven la calidad urbana y aporten valor real a las ciudades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edifica.com.py\/\" \/>\n<meta property=\"og:site_name\" content=\"Edifica Inmobiliaria\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T22:21:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edifica.com.py\/wp-content\/uploads\/2025\/09\/Logo_Principal_A-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edifica.com.py\\\/\",\"url\":\"https:\\\/\\\/edifica.com.py\\\/\",\"name\":\"\u00bfQui\u00e9nes somos?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edifica.com.py\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo_Principal_A-scaled.jpg\",\"datePublished\":\"2025-09-26T21:59:16+00:00\",\"dateModified\":\"2025-10-13T22:21:38+00:00\",\"description\":\"Edifica es una desarrolladora inmobiliaria que nace con la visi\u00f3n de transformar el interior del pa\u00eds a trav\u00e9s de proyectos que eleven la calidad urbana y aporten valor real a las ciudades.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edifica.com.py\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edifica.com.py\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo_Principal_A-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/edifica.com.py\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo_Principal_A-scaled.jpg\",\"width\":2560,\"height\":1161},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/edifica.com.py\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9nes somos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#website\",\"url\":\"https:\\\/\\\/edifica.com.py\\\/\",\"name\":\"Edifica Inmobiliaria\",\"description\":\"Edifica es una desarrolladora inmobiliaria que nace con la visi\u00f3n de transformar el interior del pa\u00eds a trav\u00e9s de proyectos que eleven la calidad urbana y aporten valor real a las ciudades.\",\"publisher\":{\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edifica.com.py\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#organization\",\"name\":\"Edifica Inmobiliaria\",\"url\":\"https:\\\/\\\/edifica.com.py\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edifica.com.py\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo_Principal_A-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/edifica.com.py\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo_Principal_A-scaled.jpg\",\"width\":2560,\"height\":1161,\"caption\":\"Edifica Inmobiliaria\"},\"image\":{\"@id\":\"https:\\\/\\\/edifica.com.py\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9nes somos?","description":"Edifica es una desarrolladora inmobiliaria que nace con la visi\u00f3n de transformar el interior del pa\u00eds a trav\u00e9s de proyectos que eleven la calidad urbana y aporten valor real a las ciudades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edifica.com.py","og_locale":"es_ES","og_type":"article","og_title":"[:es]\u00bfQui\u00e9nes somos?[:] - Edifica Inmobiliaria","og_description":"[:es]Edifica es una desarrolladora inmobiliaria que nace con la visi\u00f3n de transformar el interior del pa\u00eds a trav\u00e9s de proyectos que eleven la calidad urbana y aporten valor real a las ciudades.[:]","og_url":"https:\/\/edifica.com.py\/","og_site_name":"Edifica Inmobiliaria","article_modified_time":"2025-10-13T22:21:38+00:00","og_image":[{"width":2560,"height":1161,"url":"https:\/\/edifica.com.py\/wp-content\/uploads\/2025\/09\/Logo_Principal_A-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/edifica.com.py\/","url":"https:\/\/edifica.com.py\/","name":"\u00bfQui\u00e9nes somos?","isPartOf":{"@id":"https:\/\/edifica.com.py\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edifica.com.py\/#primaryimage"},"image":{"@id":"https:\/\/edifica.com.py\/#primaryimage"},"thumbnailUrl":"https:\/\/edifica.com.py\/wp-content\/uploads\/2025\/09\/Logo_Principal_A-scaled.jpg","datePublished":"2025-09-26T21:59:16+00:00","dateModified":"2025-10-13T22:21:38+00:00","description":"Edifica es una desarrolladora inmobiliaria que nace con la visi\u00f3n de transformar el interior del pa\u00eds a trav\u00e9s de proyectos que eleven la calidad urbana y aporten valor real a las ciudades.","breadcrumb":{"@id":"https:\/\/edifica.com.py\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edifica.com.py\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/edifica.com.py\/#primaryimage","url":"https:\/\/edifica.com.py\/wp-content\/uploads\/2025\/09\/Logo_Principal_A-scaled.jpg","contentUrl":"https:\/\/edifica.com.py\/wp-content\/uploads\/2025\/09\/Logo_Principal_A-scaled.jpg","width":2560,"height":1161},{"@type":"BreadcrumbList","@id":"https:\/\/edifica.com.py\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/edifica.com.py\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9nes somos?"}]},{"@type":"WebSite","@id":"https:\/\/edifica.com.py\/#website","url":"https:\/\/edifica.com.py\/","name":"Edifica Inmobiliaria","description":"Edifica es una desarrolladora inmobiliaria que nace con la visi\u00f3n de transformar el interior del pa\u00eds a trav\u00e9s de proyectos que eleven la calidad urbana y aporten valor real a las ciudades.","publisher":{"@id":"https:\/\/edifica.com.py\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edifica.com.py\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/edifica.com.py\/#organization","name":"Edifica Inmobiliaria","url":"https:\/\/edifica.com.py\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/edifica.com.py\/#\/schema\/logo\/image\/","url":"https:\/\/edifica.com.py\/wp-content\/uploads\/2025\/09\/Logo_Principal_A-scaled.jpg","contentUrl":"https:\/\/edifica.com.py\/wp-content\/uploads\/2025\/09\/Logo_Principal_A-scaled.jpg","width":2560,"height":1161,"caption":"Edifica Inmobiliaria"},"image":{"@id":"https:\/\/edifica.com.py\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":8,"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":101,"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/pages\/8\/revisions\/101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/media\/16"}],"wp:attachment":[{"href":"https:\/\/edifica.com.py\/index.php\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}